{"id":1042,"count":2,"description":"","link":"https:\/\/kljcharters.com\/blog\/tag\/windows\/","name":"Windows","slug":"windows","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Windows Archives - Kathleen Charters and Lawrence Charters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kljcharters.com\/blog\/tag\/windows\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows Archives - Kathleen Charters and Lawrence Charters\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kljcharters.com\/blog\/tag\/windows\/\" \/>\n<meta property=\"og:site_name\" content=\"Kathleen Charters and Lawrence Charters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@lcharters\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/tag\\\/windows\\\/\",\"url\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/tag\\\/windows\\\/\",\"name\":\"Windows Archives - Kathleen Charters and Lawrence Charters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/tag\\\/windows\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/tag\\\/windows\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/\",\"name\":\"Kathleen Charters and Lawrence Charters\",\"description\":\"Explorations large and small\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kljcharters.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Windows Archives - Kathleen Charters and Lawrence Charters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kljcharters.com\/blog\/tag\/windows\/","og_locale":"en_US","og_type":"article","og_title":"Windows Archives - Kathleen Charters and Lawrence Charters","og_url":"https:\/\/kljcharters.com\/blog\/tag\/windows\/","og_site_name":"Kathleen Charters and Lawrence Charters","twitter_card":"summary_large_image","twitter_site":"@lcharters","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kljcharters.com\/blog\/tag\/windows\/","url":"https:\/\/kljcharters.com\/blog\/tag\/windows\/","name":"Windows Archives - Kathleen Charters and Lawrence Charters","isPartOf":{"@id":"https:\/\/kljcharters.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/kljcharters.com\/blog\/tag\/windows\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kljcharters.com\/blog\/tag\/windows\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kljcharters.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows"}]},{"@type":"WebSite","@id":"https:\/\/kljcharters.com\/blog\/#website","url":"https:\/\/kljcharters.com\/blog\/","name":"Kathleen Charters and Lawrence Charters","description":"Explorations large and small","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kljcharters.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kljcharters.com\/blog\/wp-json\/wp\/v2\/tags\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kljcharters.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kljcharters.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kljcharters.com\/blog\/wp-json\/wp\/v2\/posts?tags=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}